{"id":723,"date":"2021-01-20T16:57:51","date_gmt":"2021-01-20T15:57:51","guid":{"rendered":"https:\/\/curedlighttherapy.com\/?page_id=723"},"modified":"2021-02-16T19:33:53","modified_gmt":"2021-02-16T18:33:53","slug":"pijn-verlichten-met-rood-licht-therapie","status":"publish","type":"page","link":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/","title":{"rendered":"Pijn verlichten met rood licht therapie"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-137877498\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1815780250\" class=\"text-box banner-layer x50 md-x50 lg-x50 y75 md-y80 lg-y65 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1 class=\"uppercase\"><strong>Pijn en rood licht therapie<\/strong><\/h1>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1815780250 {\n  width: 71%;\n}\n#text-box-1815780250 .text-box-content {\n  font-size: 60%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-137877498 {\n  padding-top: 70%;\n}\n#banner-137877498 .bg.bg-loaded {\n  background-image: url(https:\/\/curedlighttherapy.com\/wp-content\/uploads\/2021\/02\/CURED-light-therapy-wat-is-rood-licht-therapie-meer-leren-pijn-rugpijn-nekpijn-onderrugpijn-verlichting-medisch-natuurlijk-remedie-WEB.jpg);\n}\n#banner-137877498 .bg {\n  background-position: 40% 24%;\n}\n@media (min-width:550px) {\n  #banner-137877498 {\n    padding-top: 30%;\n  }\n}\n@media (min-width:850px) {\n  #banner-137877498 {\n    padding-top: 21%;\n  }\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-1903391094\">\n\n\t<div id=\"col-1192189289\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>Pijn is meer dan alleen een gevoel van ongemak. Het kan invloed hebben op hoe je je in het algemeen voelt. Het kan ook leiden tot psychische aandoeningen zoals depressie en angst. De hoeveelheid pijn die u ervaart, kan uw arts veel vertellen over uw algehele gezondheid.<\/p>\n<p>Pijn kan van alles zijn, van een doffe pijn tot een scherpe steek, en kan vari\u00ebren van mild tot extreem. U kunt pijn voelen in een elk deel van uw lichaam of het kan wijdverspreid zijn.<\/p>\n<h2><span data-text-color=\"alert\"><span class=\"VIiyi\" lang=\"nl\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"nl\" data-language-to-translate-into=\"en\" data-phrase-index=\"3\">Wat veroorzaakt pijn? <\/span><\/span><\/span><\/h2>\n<p>Ontsteking is de belangrijkste boosdoener als het om pijn gaat. Een effectieve ontstekingsremmer zal dus zeker de meeste, zo niet alle soorten pijn verminderen. Onderzoek toont consequent aan dat rood \/ NIR-lichttherapie (RLT) effectief is bij het verminderen van ontstekingen overal waar mitochondri\u00ebn aanwezig zijn, en dat is over heel ons lichaam.<a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29116611\/\" target=\"_blank\" rel=\"noopener\">(1)<\/a> Dat betekent dat RLT een positief effect zou moeten hebben op de meeste, zo niet alle, pijn.<\/p>\n<h2><span data-text-color=\"alert\">Ontstekingen<\/span><\/h2>\n<p>Verschillende factoren kunnen chronische ontstekingen veroorzaken, waaronder onbehandelde oorzaken van acute ontstekingen, zoals een infectie of letsel. Maar ook een auto-immuunziekte, waarbij uw immuunsysteem wordt aangetast.<\/p>\n<h2><span data-text-color=\"alert\">Hoe helpt rood licht therapie bij artritis?<\/span><\/h2>\n<p>Rood licht therapie vermindert ontstekingen door de bloedsomloop en de bloedstroom naar beschadigde weefsels te verhogen. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/28748217\/\" target=\"_blank\" rel=\"noopener\">(2)<\/a> In een recensie uit 2017 vat Dr. Michael Hamblin het volgende samen:<\/p>\n<p>&#8220;PBM is in staat de afweer van antioxidanten op te krikken en oxidatieve stress te verminderen. Er werd aangetoond dat PBM <a href=\"https:\/\/curedlighttherapy.com\/nl\/woordenboek\/\" target=\"_blank\" rel=\"noopener\">NF-kB<\/a> kan activeren in normale rustende cellen, maar in geactiveerde ontstekingscellen waren ontstekingsmarkers verminderd. Een van de meest reproduceerbare effecten van PBM is een algehele vermindering van ontstekingen, wat vooral belangrijk is bij aandoeningen van de gewrichten, traumatisch letsel, longaandoeningen en in de hersenen. &#8220;<\/p>\n<p>Artrose aan de handen kan verdikkingen aan de knokkels veroorzaken. Onderzoek toont aan dat rood licht therapie niet alleen pijn kan verminderden bij deze pati\u00ebnten, maar dat ook de vinger omtrek afnam, en de bewegelijkheid toenam. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/26833862\/\" target=\"_blank\" rel=\"noopener\">(3)<\/a><\/p>\n<p>Een studie toonde aan dat rood licht therapie de <strong>pijn met 70% verminderde<\/strong> bij pati\u00ebnten met reumato\u00efde artritis in vergelijking met de placebogroep. Pati\u00ebnten zagen ook een aanzienlijke toename van de flexibiliteit van de handpalm en een vermindering van de ochtendstijfheid. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/18003339\/\" target=\"_blank\" rel=\"noopener\">(4)<\/a><\/p>\n<h2><span data-text-color=\"alert\">Andere pijn aandoeningen<\/span><\/h2>\n<p>Daarnaast vermindert rood licht therapie de oxidatieve schade, die gewrichten kan aantasten, wat bindweefsel ten goede kan komen. Bovendien helpt RLT het produceren van meer cellulaire energie om sneller te regenereren en te genezen. <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6625994\/\" target=\"_blank\" rel=\"noopener\">(5)<\/a><\/p>\n<p>Naar schatting 80% van de bevolking heeft ooit last van lage rugpijn.<br \/>Een wetenschappelijke studie werd gedaan op infraroodtherapie voor chronische <strong>lage rugpijn<\/strong>. Ze ontdekten dat nabij-infrarood licht (meer dan 800 nm) en infrarood licht (tot 1200 nm) resulteerden in verminderde chronische lage rugpijn. (<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2539004\/\" target=\"_blank\" rel=\"noopener\">6<\/a>)<\/p>\n<p>LLLT (low-level lasertherapie) is een effectieve behandelingsmethode om pijn te verminderen bij volwassen pati\u00ebnten met <b class=\"b5\">Musculoskeletale aandoeningen<\/b> <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/26858986\/\" target=\"_blank\" rel=\"noopener\">(7) <\/a><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/28145397\/\" target=\"_blank\" rel=\"noopener\">(8)<\/a><\/p>\n<p>In 2 verschillende onderzoeken werd aangetoond dat rood licht therapie gecombineerd met stretch oefeningen, de kniepijn door <strong>osteoartritis<\/strong> aanzienlijk vermindert. <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29733117\/\" target=\"_blank\" rel=\"noopener\">(9)<\/a> <a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29480363\/\" target=\"_blank\" rel=\"noopener\">(10)<\/a><\/p>\n<p>LLLT vermindert de pijn kort na behandeling bij <strong>acute nekpijn<\/strong> en tot 22 weken na voltooiing van de behandeling bij pati\u00ebnten met <strong>chronische nekpijn<\/strong>. <a href=\"https:\/\/www.researchgate.net\/publication\/38089878_Efficacy_of_low-level_laser_therapy_in_the_management_of_neck_pain_a_systematic_review_and_meta-analysis_of_randomised_placebo_or_active-treatment_controlled_trials\" target=\"_blank\" rel=\"noopener\">(11)<\/a><\/p>\n<p>Pati\u00ebnten met <strong>fasciitis plantaris<\/strong> verlichten de <strong>hielpijn<\/strong> aanzienlijk en de uitstekende werkzaamheid houdt 3 maanden na de behandeling aan <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6370152\/\" target=\"_blank\" rel=\"noopener\">(12)<\/a><\/p>\n<h2>Herstel en terugkeer naar het spel \/ de sport<\/h2>\n<p><span class=\"VIiyi\" lang=\"nl\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"nl\" data-language-to-translate-into=\"en\" data-phrase-index=\"0\">De meeste atleten willen hun sport zo snel mogelijk hervatten na een blessure.<\/span><\/span> Ook amateur sporters en fitness fanaten hebben er baat bij om sneller te herstellen na pijnen, stijfheid of blessures.<\/p>\n<p>Rood licht therapie toonde een significante <strong>versnelling van de terugkeer naar het spel<\/strong> na twee tot zes sessies licht therapie, op de plaats van de blessure. De gemiddelde terugkeer naar het spel van geblesseerde atleten (op basis van een breed scala aan blessures) die werden behandeld met licht therapie, was 9,6 dagen, vergeleken met 19, 23 dagen in de placebogroep. De onderzoekers ontdekten dat Nabij-Infrarood licht golven de bloedstroom verbeterden, spierspasmen ontspanden, ontstekingen verminderden en de tijd dat de deelnemers pijn voelden, verminderden.(<a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4846838\/\" target=\"_blank\" rel=\"noopener\">13<\/a>)<\/p>\n<h2><span data-text-color=\"alert\"><span class=\"VIiyi\" lang=\"nl\"><span class=\"JLqJ4b ChMk0b\" data-language-for-alternatives=\"nl\" data-language-to-translate-into=\"en\" data-phrase-index=\"3\">Pijn behandelen met Rood Licht Therapie.<\/span><\/span><\/span><\/h2>\n<p>Veel klinische onderzoeken wijzen op rood licht en nabij-infrarood (NIR) licht als mogelijke behandelingen voor pijn door verschillende aandoeningen, waaronder artrose en andere gewrichtspijn, botbreuken, spierletsel, bindweefsel aandoeningen, zenuwstelsel aandoeningen en ruggenmerg aandoeningen.<\/p>\n<p>Uit studies blijkt dat rood licht therapie effectief is bij het verminderen van <a href=\"https:\/\/curedlighttherapy.com\/nl\/woordenboek\/\" target=\"_blank\" rel=\"noopener\">systemische ontstekingen<\/a> en is dus een krachtig hulpmiddel om symptomen van chronische ontstekingen te verzachten en verminderen. <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5523874\/\">(14)<\/a><\/p>\n<p>Rood licht therapie is natuurlijk, effectief, vrij van bijwerkingen en het heeft in klinische onderzoeken een groot therapeutisch potentieel aangetoond. Nabij-infrarood licht heeft het vermogen om dieper in het lichaam te door te dringen. Rood licht en Nabij-Infrarood licht zorgen er samen dus voor om het lichaam op cellulair niveau van meer energie te voorzien, waardoor het lichaam zichzelf optimaliseert.<\/p>\n<p>Ervaar de aangename, kalmerende en herstellende effecten van diep doordringende veilige lichtgolven, evenals stimulatie op celniveau van de natuurlijke genezingsprocessen van het lichaam tegen pijn. Het kan u helpen weer te genieten van uw leven, favoriete activiteiten en sport. Bovendien kan je tegelijkertijd nog genieten van de verjongende en regenererende voordelen op je huid.<\/p>\n<h2><span data-text-color=\"alert\">Bronnen:<\/span><\/h2>\n<p>(1) Ontstekingsremmende effecten van lasertherapie op laag niveau op menselijke parodontale ligamentcellen: in vitro onderzoek<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29116611\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/29116611\/<\/a><\/p>\n<p>(2) Mechanismen en toepassingen van de ontstekingsremmende effecten van fotobiomodulatie<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/28748217\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/28748217\/<\/a><\/p>\n<p>(3) Positieve effecten van lasertherapie op laag niveau (LLLT) op de osteoartritis van Bouchard en Heberden<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/26833862\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/26833862\/<\/a><\/p>\n<p>(4) Effecten van lage roodlichtbestraling op de proliferatie van mesenchymale stamcellen afgeleid van beenmerg van de rat<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/18003339\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/18003339\/<\/a><\/p>\n<p>(5) Fotobiomodulatie (660 nm) therapie vermindert oxidatieve stress en induceert BDNF-expressie in de hippocampus<br \/><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6625994\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6625994\/<\/a><\/p>\n<p>(6) Infraroodtherapie voor chronische lage rugpijn: een gerandomiseerde, gecontroleerde studie<br \/><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2539004\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2539004\/<\/a><\/p>\n<p>(7) Het gebruik van lasertherapie op laag niveau (LLLT) voor musculoskeletale pijn<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/26858986\/\">https:\/\/pubmed.ncbi.nlm.nih.gov\/26858986\/<\/a><\/p>\n<p>(8) Effecten van low-level lasertherapie op pijn bij pati\u00ebnten met musculoskeletale aandoeningen: een systematische review en meta-analyse<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/28145397\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/28145397\/<\/a><\/p>\n<p>(9) Opname van fotobiomodulatietherapie in een therapeutisch oefenprogramma voor artrose bij de knie: een placebo gecontroleerde, gerandomiseerde, klinische studie<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29733117\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/29733117\/<\/a><\/p>\n<p>(10) Echografie plus lasertherapie op laag niveau voor revalidatie van knieartrose: een gerandomiseerde, placebo-gecontroleerde studie<br \/><a href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/29480363\/\" target=\"_blank\" rel=\"noopener\">https:\/\/pubmed.ncbi.nlm.nih.gov\/29480363\/<\/a><\/p>\n<p>(11) Werkzaamheid van low-level lasertherapie bij de behandeling van nekpijn: een systematische review en meta-analyse van gerandomiseerde placebo gecontroleerde of actieve behandeling gecontroleerde onderzoeken<br \/><a href=\"https:\/\/www.researchgate.net\/publication\/38089878_Efficacy_of_low-level_laser_therapy_in_the_management_of_neck_pain_a_systematic_review_and_meta-analysis_of_randomised_placebo_or_active-treatment_controlled_trials\" target=\"_blank\" rel=\"noopener\">https:\/\/www.researchgate.net\/publication\/38089878_Efficacy_of_low-level_laser_therapy_in_the_management_of_neck_pain_a_systematic_review_and_meta-analysis_of_randomised_placebo_or_active-treatment_controlled_trials<\/a><\/p>\n<p>(12) Klinische werkzaamheid van lasertherapie op laag niveau bij plantaire fasciitis<br \/><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6370152\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6370152\/<\/a><\/p>\n<p>(13) Fototherapie verminderde het spelherstel bij geblesseerde universitaire atleten aanzienlijk: een pilotstudie<br \/><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4846838\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC4846838\/<\/a><\/p>\n<p>(14) Mechanismen en toepassingen van de ontstekingsremmende effecten van fotobiomodulatie<br \/><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5523874\/\">https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC5523874\/<\/a><\/p>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":319,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header-light.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-723","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pijn verlichten met rood licht therapie - CURED Light Therapy<\/title>\n<meta name=\"description\" content=\"pijn verlichten met licht therapie. Oorzaken &amp; voorkomen van (chronische) pijnen. CURED Rood licht therapie. Rugpijn, Nekpijn, gewrichtspijn, kniepijn\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pijn verlichten met rood licht therapie - CURED Light Therapy\" \/>\n<meta property=\"og:description\" content=\"pijn verlichten met licht therapie. Oorzaken &amp; voorkomen van (chronische) pijnen. CURED Rood licht therapie. Rugpijn, Nekpijn, gewrichtspijn, kniepijn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/\" \/>\n<meta property=\"og:site_name\" content=\"CURED Light Therapy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CuredLightTherapy\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-16T18:33:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/meer-leren-over-rood-licht-therapie\\\/pijn-verlichten-met-rood-licht-therapie\\\/\",\"url\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/meer-leren-over-rood-licht-therapie\\\/pijn-verlichten-met-rood-licht-therapie\\\/\",\"name\":\"Pijn verlichten met rood licht therapie - CURED Light Therapy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/#website\"},\"datePublished\":\"2021-01-20T15:57:51+00:00\",\"dateModified\":\"2021-02-16T18:33:53+00:00\",\"description\":\"pijn verlichten met licht therapie. Oorzaken & voorkomen van (chronische) pijnen. CURED Rood licht therapie. Rugpijn, Nekpijn, gewrichtspijn, kniepijn\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/meer-leren-over-rood-licht-therapie\\\/pijn-verlichten-met-rood-licht-therapie\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/meer-leren-over-rood-licht-therapie\\\/pijn-verlichten-met-rood-licht-therapie\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/meer-leren-over-rood-licht-therapie\\\/pijn-verlichten-met-rood-licht-therapie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Meer Leren over rood licht therapie\",\"item\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/meer-leren-over-rood-licht-therapie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pijn verlichten met rood licht therapie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/\",\"name\":\"CURED Light Therapy\",\"description\":\"Rood licht therapie\",\"publisher\":{\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/#organization\",\"name\":\"CURED Light Therapy\",\"url\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/curedlighttherapy.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Cured-Light-Therapy-LOGO-red-light-therapy-rood-licht-therapie.png\",\"contentUrl\":\"https:\\\/\\\/curedlighttherapy.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/Cured-Light-Therapy-LOGO-red-light-therapy-rood-licht-therapie.png\",\"width\":2000,\"height\":1714,\"caption\":\"CURED Light Therapy\"},\"image\":{\"@id\":\"https:\\\/\\\/curedlighttherapy.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CuredLightTherapy\",\"https:\\\/\\\/www.instagram.com\\\/curedlighttherapy\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC88kdHwQ34KO-vJWaIBTWMA\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pijn verlichten met rood licht therapie - CURED Light Therapy","description":"pijn verlichten met licht therapie. Oorzaken & voorkomen van (chronische) pijnen. CURED Rood licht therapie. Rugpijn, Nekpijn, gewrichtspijn, kniepijn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/","og_locale":"nl_NL","og_type":"article","og_title":"Pijn verlichten met rood licht therapie - CURED Light Therapy","og_description":"pijn verlichten met licht therapie. Oorzaken & voorkomen van (chronische) pijnen. CURED Rood licht therapie. Rugpijn, Nekpijn, gewrichtspijn, kniepijn","og_url":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/","og_site_name":"CURED Light Therapy","article_publisher":"https:\/\/www.facebook.com\/CuredLightTherapy","article_modified_time":"2021-02-16T18:33:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/","url":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/","name":"Pijn verlichten met rood licht therapie - CURED Light Therapy","isPartOf":{"@id":"https:\/\/curedlighttherapy.com\/nl\/#website"},"datePublished":"2021-01-20T15:57:51+00:00","dateModified":"2021-02-16T18:33:53+00:00","description":"pijn verlichten met licht therapie. Oorzaken & voorkomen van (chronische) pijnen. CURED Rood licht therapie. Rugpijn, Nekpijn, gewrichtspijn, kniepijn","breadcrumb":{"@id":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/pijn-verlichten-met-rood-licht-therapie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/curedlighttherapy.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Meer Leren over rood licht therapie","item":"https:\/\/curedlighttherapy.com\/nl\/meer-leren-over-rood-licht-therapie\/"},{"@type":"ListItem","position":3,"name":"Pijn verlichten met rood licht therapie"}]},{"@type":"WebSite","@id":"https:\/\/curedlighttherapy.com\/nl\/#website","url":"https:\/\/curedlighttherapy.com\/nl\/","name":"CURED Light Therapy","description":"Rood licht therapie","publisher":{"@id":"https:\/\/curedlighttherapy.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/curedlighttherapy.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/curedlighttherapy.com\/nl\/#organization","name":"CURED Light Therapy","url":"https:\/\/curedlighttherapy.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/curedlighttherapy.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/curedlighttherapy.com\/wp-content\/uploads\/2020\/09\/Cured-Light-Therapy-LOGO-red-light-therapy-rood-licht-therapie.png","contentUrl":"https:\/\/curedlighttherapy.com\/wp-content\/uploads\/2020\/09\/Cured-Light-Therapy-LOGO-red-light-therapy-rood-licht-therapie.png","width":2000,"height":1714,"caption":"CURED Light Therapy"},"image":{"@id":"https:\/\/curedlighttherapy.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CuredLightTherapy","https:\/\/www.instagram.com\/curedlighttherapy\/","https:\/\/www.youtube.com\/channel\/UC88kdHwQ34KO-vJWaIBTWMA\/videos"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/pages\/723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/comments?post=723"}],"version-history":[{"count":16,"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/pages\/723\/revisions"}],"predecessor-version":[{"id":1225,"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/pages\/723\/revisions\/1225"}],"up":[{"embeddable":true,"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/pages\/319"}],"wp:attachment":[{"href":"https:\/\/curedlighttherapy.com\/nl\/wp-json\/wp\/v2\/media?parent=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}